{"id":2365,"date":"2026-03-01T19:57:43","date_gmt":"2026-03-01T18:57:43","guid":{"rendered":"https:\/\/ucjgalsace.org\/cms\/?p=2365"},"modified":"2026-05-12T07:13:35","modified_gmt":"2026-05-12T06:13:35","slug":"les-flyers-des-sejours-2026-sont-arrives-2","status":"publish","type":"post","link":"https:\/\/ucjgalsace.org\/cms\/les-flyers-des-sejours-2026-sont-arrives-2\/","title":{"rendered":"Les flyers des s\u00e9jours 2026 sont arriv\u00e9s !"},"content":{"rendered":"<div id=\"pl-2365\"  class=\"panel-layout\" ><div id=\"pg-2365-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-2365-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2365-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><h3 class=\"widget-title\">Tous les s\u00e9jours 2026<\/h3>\t\t\t<div class=\"textwidget\"><p><a href=\"https:\/\/ucjgalsace.org\/cms\/les-camps-et-colos-ete-2026\/\" target=\"_blank\" rel=\"noopener\">Tous les s\u00e9jours 2026<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/pre-inscription-a-un-camp\/\">Pr\u00e9-inscription<\/a><\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-2365-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-2365-0-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"1\" ><h3 class=\"widget-title\">Explor&rsquo;Nature 6-9 ans<\/h3>\t\t\t<div class=\"textwidget\"><p>Explor&rsquo;Nature du 13 au 26 juillet 2026, pour les 6-9 ans, \u00e0 la Hoube (57). Id\u00e9al pour une premi\u00e8re exp\u00e9rience en colo.<\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/1-Flyer-Explo-2026-R.pdf\" target=\"_blank\" rel=\"noopener\">Flyer Explor&rsquo;Nature 6-9 ans<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/pre-inscription-a-un-camp\/\">pr\u00e9-inscription<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/verso-2026-sejours.pdf\">Tarifs et informations<\/a><\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-2365-0-2\"  class=\"panel-grid-cell\" ><div id=\"panel-2365-0-2-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"2\" ><h3 class=\"widget-title\">Graines de Talents 10-12 ans<\/h3>\t\t\t<div class=\"textwidget\"><p>Graines de Talents\u00a0 pour les 10-12 ans, du 13 au 26 juillet 2026 \u00e0 La Hoube (57)<\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/2-flyers-GDT-2026-R.pdf\" target=\"_blank\" rel=\"noopener\">Flyer Graines de Talents 10-12 ans<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/pre-inscription-a-un-camp\/\">Pr\u00e9-inscription<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/verso-2026-sejours.pdf\">Tarifs et informations<\/a><\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-2365-0-3\"  class=\"panel-grid-cell\" ><div id=\"panel-2365-0-3-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"3\" ><h3 class=\"widget-title\">Les 12 travaux de Williams 7-12 ans<\/h3>\t\t\t<div class=\"textwidget\"><p>Les 12 Travaux de Williams pour les 7-12 ans, du 28 juillet au 10 ao\u00fbt 2026 \u00e0 la maison YMCA UCJG Foss\u00e9 des treize \u00e0 Salm (67)<\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/3-Flyer-12TW-2026-R.pdf\" target=\"_blank\" rel=\"noopener\">Les 12 travaux de Williams 7-12 ans<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/pre-inscription-a-un-camp\/\">Pr\u00e9-inscription<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/verso-2026-sejours.pdf\">Tarifs et informations<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-2365-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-2365-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2365-1-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"4\" ><h3 class=\"widget-title\">Collectiv\u2019Ado 12-14 ans<\/h3>\t\t\t<div class=\"textwidget\"><p>Collectiv&rsquo;Ado pour les 12-14 ans du 13 au 26 juillet 2026 au Camp Joubert des YMCA (43)<\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/4-Flyer-CollA-Joubert-2026-R.pdf\" target=\"_blank\" rel=\"noopener\">Flyer Collectiv&rsquo;Ado 12-14 ans<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/pre-inscription-a-un-camp\/\">Pr\u00e9-inscription<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/verso-2026-sejours.pdf\">Tarifs et informations<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-2365-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-2365-1-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"5\" ><h3 class=\"widget-title\">Anim&rsquo;Ado 15-17 ans<\/h3>\t\t\t<div class=\"textwidget\"><p>Anim&rsquo;Ado pour les 15-17 ans du 13 au 26 juillet 2026 au Camp Joubert des YMCA (43)<\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/5-Flyer-Animado-2026-R.pdf\" target=\"_blank\" rel=\"noopener\">Flyer Anim&rsquo;ado 15-17 ans<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/pre-inscription-a-un-camp\/\">Pr\u00e9-inscription<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/verso-2026-sejours.pdf\">Tarifs et informations<\/a><\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-2365-1-2\"  class=\"panel-grid-cell\" ><div id=\"panel-2365-1-2-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"6\" ><h3 class=\"widget-title\">Cultures crois\u00e9es sur l&rsquo;Ile de Borkum 15-17 ans<\/h3>\t\t\t<div class=\"textwidget\"><p>Cultures crois\u00e9es sur l&rsquo;Ile de Borkum en Allemagne \u00e0 la mer du Nord.<\/p>\n<p>S\u00e9jour Franco-allemand pour des jeunes fran\u00e7ais, allemands et ukrainiens.\u00a0Que tu parles allemand ou non<\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/6-Flyer-FA-2026-Compl-R.pdf\" target=\"_blank\" rel=\"noopener\">Cultures crois\u00e9es sur l&rsquo;Ile de Borkum 15-17 ans<\/a><\/p>\n<p><a href=\"https:\/\/ucjgalsace.org\/cms\/pre-inscription-a-un-camp\/\">pr\u00e9-inscription<\/a><br \/>\n<a href=\"https:\/\/ucjgalsace.org\/cms\/wp-content\/uploads\/2026\/03\/verso-2026-sejours-FAU.pdf\">Tarif et Informations<\/a><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tous les s\u00e9jours 2026 Pr\u00e9-inscription Explor&rsquo;Nature du 13 au 26 juillet 2026, pour les 6-9 ans, \u00e0 la Hoube (57). Id\u00e9al pour une premi\u00e8re exp\u00e9rience en colo. Flyer Explor&rsquo;Nature 6-9 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[67,4],"tags":[],"class_list":["post-2365","post","type-post","status-publish","format-standard","hentry","category-camps-des-annees-passees","category-sejours"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8nbU3-C9","_links":{"self":[{"href":"https:\/\/ucjgalsace.org\/cms\/wp-json\/wp\/v2\/posts\/2365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ucjgalsace.org\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ucjgalsace.org\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ucjgalsace.org\/cms\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ucjgalsace.org\/cms\/wp-json\/wp\/v2\/comments?post=2365"}],"version-history":[{"count":27,"href":"https:\/\/ucjgalsace.org\/cms\/wp-json\/wp\/v2\/posts\/2365\/revisions"}],"predecessor-version":[{"id":2465,"href":"https:\/\/ucjgalsace.org\/cms\/wp-json\/wp\/v2\/posts\/2365\/revisions\/2465"}],"wp:attachment":[{"href":"https:\/\/ucjgalsace.org\/cms\/wp-json\/wp\/v2\/media?parent=2365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ucjgalsace.org\/cms\/wp-json\/wp\/v2\/categories?post=2365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ucjgalsace.org\/cms\/wp-json\/wp\/v2\/tags?post=2365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}